{"id":2014,"date":"2022-04-04T11:17:53","date_gmt":"2022-04-04T14:17:53","guid":{"rendered":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/pcomunidad2022\/"},"modified":"2022-04-04T11:17:53","modified_gmt":"2022-04-04T14:17:53","slug":"pcomunidad2022","status":"publish","type":"post","link":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/pcomunidad2022\/","title":{"rendered":"Programa Comunidad 2022"},"content":{"rendered":"<div class=\"mision\">\n    &nbsp;<\/p>\n<div class=\"titulo-secciones\">\n        Programa Comunidad<a class=\"ancla\" id=\"igualdad\" name=\"comunidad\">&nbsp;<\/a><\/div>\n<p>    &nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-sm-1\">\n            &nbsp;<\/div>\n<div class=\"col-sm-10\">\n<div class=\"titulo-secciones\">\n                Tenencia Animal Responsable<\/div>\n<div class=\"titulo-secciones\">\n                Rol Social del Veterinario<\/div>\n<div class=\"titulo-secciones\">\n                Promoviendo el bienestar de la convivencia humano &#8211; animal &#8211; ambiente<\/div>\n<div class=\"row\">\n<div class=\"col-sm-1\">\n                    &nbsp;<\/div>\n<div class=\"col-sm-10\">\n<p>\n                        &nbsp;<\/p>\n<p>\n                        <b>QUIENES SOMOS?<\/b><\/p>\n<p>                    &nbsp;<\/p>\n<p>\n                        <b>TALLERES<\/b> (los talleres presenciales se encuentran suspendidos por el momento)<\/p>\n<ul>\n<li>\n                            Talleres para estudiantes de Veterinaria:<\/li>\n<li>\n                            &#8211; Talleres virtuales (link a los talleres)<br \/>\n                            &#8211; Sincronicos<br \/>\n                            &#8211; Asincronicos<br \/>\n                            &#8211; Talleres presenciales<\/p>\n<p>\n                                &nbsp;<\/p>\n<\/li>\n<li>\n                            Talleres para escuelas:<\/li>\n<li>\n                            &#8211; Talleres virtuales<br \/>\n                            &#8211; Sincronicos: son talleres que se realizan mediante las plataformas: Google Meet y Zoom, junto con maestros, Veterinarios y alumnos de la carrera.<br \/>\n                            &#8211; Asincronicos: contamos con material como actividades, juegos y cuentos para realizar de forma asincronica, sin necesidad de contar con conexion a internet.<br \/>\n                            &nbsp; &nbsp; &nbsp; Actividades:<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Vamos a pasear?<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Como hacer una chapita casera?<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Como hacer un bolsero?<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Poesia<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Cuento: Fiorella<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Imagenes para hacer el cuento<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; Juegos:<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Ruleta<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Juego de la Oca<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; Promotor Responsable:<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Comu Tips<br \/>\n                            &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; Guia Rapida<br \/>\n                            &nbsp;<\/p>\n<p>\n                                <b>TENENCIA RESPONSABLE<\/b><\/p>\n<\/li>\n<li>\n                            Tenencia animal responsable para estudiantes de Veterinaria<\/li>\n<li>\n                            Tenencia animal responsable para Escuelas<\/li>\n<p>                        &nbsp;<\/ul>\n<p>\n                        <b>MISION<\/b><\/p>\n<p>\n                        Comunicar a la comunidad conocimientos sobre la tenencia animal responsable. Ofrecer herramientas para que la convivencia interespecie sea desde el respeto y el conocimiento de las especies que la conforman.<\/p>\n<p>                    &nbsp;<\/p>\n<p>\n                        <b>VISION<\/b><\/p>\n<p>\n                        Brindar informaci\u00f3n fidedigna y actualizada sobre tenencia animal responsable.<\/p>\n<p>                    &nbsp;<\/p>\n<p>\n                        <b>HISTORIA<\/b><\/p>\n<p>\n                        El Programa Comunidad se cre\u00f3 en el a\u00f1o 2016 (Resol FCV &#8211; CD 2260\/16) como respuesta a las necesidades de la comunidad sobre los cuidados de la salud de los animales. Tambi\u00e9n con la idea de concientizar a las personas sobre la relaci\u00f3n interespecie y la responsabilidad que eso representa&#8230;<\/p>\n<p>\n                        &nbsp;<\/p>\n<p>\n                        Si quer\u00e9s formar parte del equipo contactate a <a href=\"mailto:pcomunidad@fvet.uba.ar\" target=\"_blank\" rel=\"noopener\">pcomunidad@fvet.uba.ar<\/a><\/p>\n<p>                    <!--\n                    \n\n<p>\n                        &nbsp;<\/p>\n\n\n        \n                    \n\n<p>\n                        <iframe loading=\"lazy\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"180\" src=\"https:\/\/www.youtube.com\/embed\/\" width=\"300\"><\/iframe><\/p>\n\n\n        \n                    \n\n<p>\n                        <iframe loading=\"lazy\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"180\" src=\"https:\/\/www.youtube.com\/embed\/_ucp2Xrarhg\" width=\"300\">&nbsp;<\/iframe><\/p>\n\n\n                    --><\/p>\n<p>\n                        &nbsp;<\/p>\n<p>                <!--\n\n<p>\n        El Programa Comunidad tiene dos ejes de acci\u00f3n: <\/p>\n\n\n        \n        \n\n<h3>\n        <img class=\"img-circle img-responsive listado2\"  data-cke-saved-src=\"<?= fileurl('sites\/default\/files\/pictures\/boton.png') ?>\" src=\"<?= fileurl('sites\/default\/files\/pictures\/boton.png') ?>\" \/><b>Peque\u00f1os animales<\/b><\/h3>\n\n\n        \n\n<ul>\n        \n\n<li>\n            <iframe loading=\"lazy\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"180\" src=\"https:\/\/www.youtube.com\/embed\/4YV8w0-3RB0\" width=\"300\"><\/iframe>\n        <\/li>\n\n\n        \n\n<li>\n            -<b>En la Escuela Infantil el Hornero<\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/354416525127255\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/354416525127255\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        \n\n<li>\n            -<b>En el Municipio de Esteban Echeverr\u00eda<\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/184062772499174\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/184062772499174\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        \n\n<li>\n            -<b>Con el Voluntariado de Alumnos Gu\u00edas<\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/755808991439931\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/755808991439931\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        \n\n<li>\n            -<b>En el Jard\u00edn 916 del Municipio de Esteban Echeverr\u00eda<\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/426555257869707\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/426555257869707\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        \n\n<li>\n            -<b>En Isla Maciel <\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/263301067844883\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/263301067844883\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        \n        \n\n<li>\n            -<b>En el Municipio de Esteban Echeverr\u00eda<\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/2080241865526231\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/2080241865526231\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        \n\n<li>\n            -<b>En el barrio de La Carbonilla<\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/1987646421452443\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/1987646421452443\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        <\/ul>\n\n\n        \n        \n\n<p>\n        &nbsp;<\/p>\n\n\n        \n        \n\n<h3>\n        <img class=\"img-circle img-responsive listado2\"  data-cke-saved-src=\"<?= fileurl('sites\/default\/files\/pictures\/boton.png') ?>\" src=\"<?= fileurl('sites\/default\/files\/pictures\/boton.png') ?>\" \/><b>Equinos<\/b>\n        <\/h3>\n\n\n        \n        \n        \n\n<ul>\n        \n\n<li>\n            <iframe loading=\"lazy\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"180\" src=\"https:\/\/www.youtube.com\/embed\/_ucp2Xrarhg\" width=\"300\"><\/iframe>\n        <\/li>\n\n\n        \n\n<li>\n            -<b>Equinos en el Municipio de Esteban Echeverr\u00eda<\/b><br \/>\n            <a data-cke-saved-href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/2106161339600950\/\" href=\"https:\/\/www.facebook.com\/1496859870531103\/videos\/2106161339600950\/\" target=\"_blank\" rel=\"noopener\">ver video<\/a>\n        <\/li>\n\n\n        <\/ul>\n\n\n        \n        \n\n<p>\n        &nbsp;<\/p>\n\n\n        \n        \n        \n        \n\n<div class=\"collapse\" id=\"verigualdad\">\n        &nbsp;<\/div>\n\n\n        <\/div>\n\n\n        \n        \n\n<div class=\"col-sm-1\">\n        &nbsp;<\/div>\n\n\n        <\/div>\n\n\n        <br \/>\n        &nbsp;\n        <\/div>\n\n\n                    -->\n                <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Programa Comunidad&nbsp; &nbsp; &nbsp; Tenencia Animal Responsable Rol Social del Veterinario Promoviendo el bienestar de la convivencia humano &#8211; animal &#8211; ambiente &nbsp; &nbsp; QUIENES SOMOS? &nbsp; TALLERES (los talleres presenciales se encuentran suspendidos por el momento) Talleres para estudiantes de Veterinaria: &#8211; Talleres virtuales (link a los talleres) &#8211; Sincronicos &#8211; Asincronicos &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2014","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:58:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/posts\/2014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2014"}],"version-history":[{"count":0,"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/posts\/2014\/revisions"}],"wp:attachment":[{"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.sitios.fvet.uba.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}